{"id":10328,"date":"2023-07-17T10:41:34","date_gmt":"2023-07-17T09:41:34","guid":{"rendered":"https:\/\/strategiesconsultingfirm.com\/?p=10328"},"modified":"2023-08-30T11:11:35","modified_gmt":"2023-08-30T10:11:35","slug":"faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats","status":"publish","type":"post","link":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/","title":{"rendered":"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0?"},"content":{"rendered":"\n<p class=\"has-small-font-size wp-block-paragraph\" style=\"font-style:italic;font-weight:800;text-transform:none\"><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:23px;font-style:italic;font-weight:800\"><em style=\"\">I &#8211; ETAT DES LIEUX DE <\/em><em>INS\u00c9CURIT\u00c9 ALIMENTAIRE EN AFRIQUE<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De fa\u00e7on concr\u00e8te, l\u2019ins\u00e9curit\u00e9 alimentaire existe lorsque des personnes n&#8217;ont pas un acc\u00e8s physique ou \u00e9conomique durable \u00e0 une nourriture suffisamment s\u00fbre, nutritive et socialement acceptable pour mener une vie saine et productive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ins\u00e9curit\u00e9 alimentaire connait plusieurs degr\u00e9s de s\u00e9v\u00e9rit\u00e9 comme l\u2019indique le tableau ci \u2013 dessous&nbsp;:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim2-1024x576.jpg\" alt=\"\" class=\"wp-image-10329\" srcset=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim2-1024x576.jpg 1024w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim2-300x169.jpg 300w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim2-768x432.jpg 768w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim2-1536x864.jpg 1536w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim2-2048x1152.jpg 2048w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim2-900x506.jpg 900w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim2-600x337.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En fin 2022, dans une d\u00e9claration commune, le FAO, l\u2019Unicef et le PAM pr\u00e9voyaient que l\u2019Afrique centrale et l\u2019Afrique de l\u2019Ouest atteindraient en 2023 le record de 48 millions de personnes (dont 9 millions d\u2019enfants) en situation d\u2019ins\u00e9curit\u00e9 alimentaire si rien n\u2019\u00e9tait fait<a id=\"_ednref1\" href=\"#_edn1\"><sup>[i]<\/sup><\/a>. Une estimation \u00e0 la hausse de pr\u00e8s de 13 millions, en comparaison aux 35 millions de victimes (dont 6,7 millions d\u2019enfants) recens\u00e9es en 2022 par le Cadre harmonis\u00e9 d\u2019analyse de la s\u00e9curit\u00e9 alimentaire. Un chiffre correspondant \u00e0 8 % de la population de ces parties de l\u2019Afrique incapables de satisfaire leurs besoins alimentaires et nutritionnels de base.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 le d\u00e9ploiement de nombreuses initiatives et la mobilisation des fonds importants par les Etats et les partenaires au d\u00e9veloppement depuis de nombreuses ann\u00e9es, la situation semble s\u2019aggraver au fil des ans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2023, d\u2019apr\u00e8s le rapport global sur les crises alimentaires dans le monde, la situation en Afrique demeurait pr\u00e9occupante&nbsp;:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim3-1024x576.jpg\" alt=\"\" class=\"wp-image-10331\" style=\"width:840px;height:473px\" width=\"840\" height=\"473\" srcset=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim3-1024x576.jpg 1024w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim3-300x169.jpg 300w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim3-768x432.jpg 768w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim3-1536x864.jpg 1536w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim3-2048x1152.jpg 2048w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim3-900x506.jpg 900w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim3-600x337.jpg 600w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Comment comprendre cette aggravation de la situation&nbsp;? Cette incapacit\u00e9 \u00e0 apporter des solutions durables \u00e0 la crise alimentaire en Afrique ne r\u00e9side-t-elle pas dans le caract\u00e8re non fonctionnel des Etats&nbsp;? En d\u2019autres termes, l\u2019Etat fonctionnel peut \u2013 il \u00eatre une r\u00e9ponse pour surmonter l\u2019ins\u00e9curit\u00e9 alimentaire chronique en Afrique ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Notre hypoth\u00e8se&nbsp;:&nbsp; Le d\u00e9ficit d\u2019Etat Fonctionnel est le facteur explicatif majeur de la persistance des crises alimentaires en Afrique<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:23px;font-style:italic;font-weight:800\"><em style=\"\">II &#8211; NOTRE HYPOTH\u00c8SE&nbsp;: LE <\/em><em>D\u00c9FICIT D\u2019<em>\u00c9<\/em>TAT FONCTIONNEL EST UN FACTEUR EXPLICATIF MAJEUR DE LA PERSISTANCE ET DE L\u2019AGGRAVATION DES CRISES ALIMENTAIRES EN AFRIQUE&nbsp;!<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Les causes traditionnelles de l\u2019ins\u00e9curit\u00e9 alimentaires dans le monde<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De fa\u00e7on g\u00e9n\u00e9rale et traditionnelle, on distingue cinq principales causes de l\u2019ins\u00e9curit\u00e9 alimentaire dans le monde&nbsp;:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim4-1024x576.jpg\" alt=\"\" class=\"wp-image-10333\" srcset=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim4-1024x576.jpg 1024w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim4-300x169.jpg 300w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim4-768x432.jpg 768w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim4-1536x864.jpg 1536w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim4-2048x1152.jpg 2048w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim4-900x506.jpg 900w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim4-600x337.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le Rapport mondial sur les crises alimentaires de 2021, r\u00e9v\u00e8le que les conflits et l\u2019ins\u00e9curit\u00e9 ont plong\u00e9 pr\u00e8s de 100 millions de personnes dans le monde dans une ins\u00e9curit\u00e9 alimentaire aigu\u00eb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces crises s\u00e9curitaires \u00e9taient accompagn\u00e9es d\u2019un choc \u00e9conomique qui a affect\u00e9 40 millions de personnes, et des conditions m\u00e9t\u00e9orologiques extr\u00eames qui ont affect\u00e9es 16 millions de personnes<a href=\"#_edn2\">[ii]<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Selon ce rapport, les causes des crises alimentaires ne doivent pas \u00eatre prises de fa\u00e7on isol\u00e9es mais plut\u00f4t \u00eatre consid\u00e9r\u00e9es comme des facteurs qui s\u2019entrem\u00ealent mutuellement et surviennent tr\u00e8s souvent de fa\u00e7on cyclique. Elles affectent ainsi les strat\u00e9gies d\u2019adaptation et la r\u00e9silience des populations \u00e0 travers le monde et entraine davantage de dommages dans des pays fragiles comme ceux d\u2019Afrique.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#007cba;font-size:25px\"><strong><em>Les facteurs aggravant de la crise alimentaire en Afrique<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de ces cinq causes \u00e9voqu\u00e9es pr\u00e9c\u00e9demment, les pays africains connaissent d\u2019autres facteurs sp\u00e9cifiques qui aggravent les crises alimentaires&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Facteur 1&nbsp;: L\u2019insuffisant d\u00e9veloppement du secteur agricole en Afrique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les gouvernements africains n&#8217;ont pas mis en \u0153uvre des politiques qui emp\u00eachent les crises alimentaires de se reproduire. La plupart des pays n\u2019ont pas r\u00e9ussi \u00e0 mettre en place des politiques agricoles durables permettant d&#8217;assurer la s\u00e9curit\u00e9 alimentaire \u00e0 long terme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon une \u00e9tude men\u00e9e par OXFAM en 2021, 39 Etats africains ont r\u00e9duit de 18 %, la part de leur budget consacr\u00e9 \u00e0 l\u2019agriculture entre 2019 et 2021, 26 d\u2019entre eux, soient les deux tiers ont consacr\u00e9 moins de 5 % de leur budget national \u00e0 l\u2019agriculture<a href=\"#_edn3\">[iii]<\/a>. Or il y a 20 ans, tous ces Etats s\u2019\u00e9taient engag\u00e9s dans le cadre du protocole de Maputo, \u00e0 consacrer au moins 10 % de leur budget national \u00e0 l\u2019agriculture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Facteur 2&nbsp;: La forte croissance d\u00e9mographique de l\u2019Afrique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actuellement, l&#8217;Afrique est le deuxi\u00e8me plus grand continent du monde avec une population d&#8217;environ 1,216 milliard de personnes et un taux de croissance annuel estim\u00e9 \u00e0 3,7 %. La demande de production alimentaire s&#8217;est donc accrue avec cette augmentation flagrante de la population. Il en r\u00e9sulte une ins\u00e9curit\u00e9 alimentaire, car la production ne r\u00e9pond pas \u00e0 la demande en raison de l&#8217;augmentation constante de la population.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Facteur 3&nbsp;: L\u2019exode rural et l&#8217;urbanisation galopante en Afrique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;augmentation de l&#8217;exode rural due \u00e0 l&#8217;urbanisation joue un r\u00f4le cl\u00e9 dans l&#8217;\u00e9mergence de l&#8217;ins\u00e9curit\u00e9 alimentaire en Afrique. Le niveau d\u2019urbanisation en Afrique, actuellement de 44,4 %, atteindra 58,9 % d\u2019ici 2050. De 500 millions actuellement, ils seront 950 millions en 2050.&nbsp; Et pourtant, la main d\u2019\u0153uvre agricole vit dans les milieux ruraux<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-decoration:underline\"><strong>Facteur 4&nbsp;: Les crises internationales entra\u00eenant des r\u00e9percussions fortes en Afrique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La majorit\u00e9 des pays africains sont d\u00e9pendants des autres r\u00e9gions du monde pour l\u2019importation des denr\u00e9es alimentaires. La perturbation des chaines de valeurs du fait de la COVID 19 a fait croitre d\u2019au moins 30 millions le nombre de personnes suppl\u00e9mentaires tomb\u00e9es dans la pauvret\u00e9. La guerre entre la Russie et l\u2019Ukraine entra\u00eene aussi des cons\u00e9quences majeures sur l\u2019ins\u00e9curit\u00e9 alimentaire en Afrique. L&#8217;Afrique d\u00e9pend de l&#8217;importation de certains produits en provenance de pays d&#8217;Europe et d&#8217;autres r\u00e9gions en guerre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Etats non fonctionnels&nbsp;: une autres des causes principales de la r\u00e9currence des crises alimentaires en Afrique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si l\u2019on ne peut nier la pertinence des causes et des facteurs \u00e9voqu\u00e9s plus haut, on peut avancer qu\u2019un autre \u00e9l\u00e9ment cl\u00e9 doit \u00eatre pris en compte. Il s\u2019agit du caract\u00e8re fonctionnel des Etats qui peut permettre, dans la dur\u00e9e, d\u2019anticiper, d\u2019att\u00e9nuer et voir de surmonter ces diff\u00e9rentes crises.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le dysfonctionnement de l&#8217;\u00c9tat est la cause la plus fr\u00e9quente des probl\u00e8mes de d\u00e9veloppement en Afrique. Le facteur cl\u00e9 indispensable auquel les citoyens, les institutions et les partenaires de d\u00e9veloppement africains n&#8217;accordent pas suffisamment d&#8217;attention est l&#8217;\u00c9tat africain fonctionnel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019incapacit\u00e9 des Etats \u00e0 planifier et bien ex\u00e9cuter des politiques pertinentes est un probl\u00e8me majeur. La persistance de conflits, de l\u2019ins\u00e9curit\u00e9 et autres crises majeures dans ces pays n\u2019aide pas \u00e0 faire face efficacement \u00e0 la crise alimentaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019on ne peut plus penser des solutions durables sans prendre en compte le niveau de fonctionnalit\u00e9 des Etats dans lesquels surviennent les crises. Ne pas le faire, c\u2019est se condamner \u00e0 ne jamais rompre le cycle des d\u00e9faillances et des d\u00e9pendances que l\u2019on observe depuis des d\u00e9cennies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prise en compte de la fonctionnalit\u00e9 de l\u2019Etat doit \u00eatre un facteur essentiel pour les interventions en faveur du d\u00e9veloppement en Afrique si l\u2019on veut obtenir des r\u00e9sultats favorables aujourd\u2019hui.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si l\u2019on veut obtenir des r\u00e9sultats meilleurs, il faut sans doute am\u00e9liorer la conception et le d\u00e9ploiement des strat\u00e9gies qui visent \u00e0 doter ces Etats de capacit\u00e9s \u00e0 faire face aux diff\u00e9rents d\u00e9fis qui se posent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Qu\u2019est-ce que nous entendons par Etat fonctionnel et en quoi sa prise en compte peut-elle participer \u00e0 r\u00e9soudre le probl\u00e8me de la sous-alimentation en Afrique&nbsp;?<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:23px;font-style:italic;font-weight:800\"><em>III &#8211; LE CONCEPT D\u2019ETAT FONCTIONNEL EN AFRIQUE<\/em><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li style=\"text-decoration:underline\"><strong>Qu\u2019est-ce qu\u2019un Etat fonctionnel&nbsp;?<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Etat fonctionnel est un concept d\u00e9velopp\u00e9 par le Cabinet STRATEGIES sur la base de r\u00e9flexions profondes sur le fonctionnement des Etats en Afrique et plus de 28 ans d\u2019exp\u00e9riences dans l\u2019accompagnement tant des Etats que des organismes de d\u00e9veloppement dans l\u2019\u00e9laboration et la mise en \u0153uvre des strat\u00e9gies de gouvernance aux niveaux continental, sous-r\u00e9gional, national et local. L\u2019Etat fonctionnel repose sur trois piliers cl\u00e9s \u00e0 savoir : la pr\u00e9sence, la s\u00e9curit\u00e9 et la s\u00fbret\u00e9, et l\u2019espoir.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim5-1024x576.jpg\" alt=\"\" class=\"wp-image-10335\" srcset=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim5-1024x576.jpg 1024w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim5-300x169.jpg 300w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim5-768x432.jpg 768w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim5-1536x864.jpg 1536w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim5-2048x1152.jpg 2048w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim5-900x506.jpg 900w, https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim5-600x337.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ces diff\u00e9rents \u00e9l\u00e9ments pr\u00e9sent\u00e9s bri\u00e8vement peuvent \u00eatre d\u00e9clin\u00e9s sur diff\u00e9rents aspects de la gouvernance. Dans le cas d\u2019esp\u00e8ce, il s\u2019agit de ressortir la plus-value de l\u2019Etat fonctionnel dans la dynamique de r\u00e9solution durable des situations de crises alimentaires successives auxquelles les pays africains sont confront\u00e9s depuis des ann\u00e9es.<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\" start=\"2\">\n<li style=\"text-decoration:underline\"><strong>Ce qui change avec la prise en compte de l\u2019Etat dans la gestion des crises alimentaires en Afrique<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Les situations de crises alimentaires appellent g\u00e9n\u00e9ralement \u00e0 des solutions d\u2019urgences pour g\u00e9rer les aspects humanitaires (fourniture des aliments aux sinistr\u00e9s) et \u00e0 des solutions de d\u00e9veloppement (chaines de valeurs agricoles, Intrants agricoles, zones de productions, gestion des sols et des stocks, etc.) pour r\u00e9gler le probl\u00e8me \u00e0 moyen et \u00e0 long terme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prise en compte effective de ces deux aspects fait d\u00e9j\u00e0 partie de l\u2019agenda des Etats et des partenaires au d\u00e9veloppement qui sont les principaux acteurs \u00e0 se d\u00e9ployer dans le cadre de la r\u00e9solution de ces crises.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seulement, dans la r\u00e9alit\u00e9, on observe que l\u2019accent est mis sur l\u2019apport de solutions urgentes et la r\u00e9ussite sectorielle de certains projets agricoles sans qu\u2019il y ait un impact d\u00e9cisif sur l\u2019Etat, ce qui assurerait dans l\u2019avenir des solutions durables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quand bien m\u00eame les moyens sont mobilis\u00e9s et mis \u00e0 la disposition des Etats pour g\u00e9rer les aspects durables, il n\u2019y a pas de r\u00e9sultats comme c\u2019est le cas avec les situations d\u2019urgences o\u00f9 les organisations humanitaires internationales et nationales sont tr\u00e8s souvent sur le terrain eux-m\u00eames pour mener les op\u00e9rations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cons\u00e9quence, les moyens mobilis\u00e9s pour les solutions \u00e0 moyen et long terme sont parfois utilis\u00e9s sans que cela ne produise des r\u00e9sultats escompt\u00e9s.&nbsp; Au terme du processus, on a des Etats plus endett\u00e9s, toujours d\u00e9pendants et les m\u00eames urgences \u00e0 g\u00e9rer avec plus de gravit\u00e9 comme c\u2019est le cas avec la crise alimentaire actuellement.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:23px;font-style:italic;font-weight:800\"><em style=\"\">IV \u2013 VALEUR <\/em><em>AJOUT\u00c9E DU CONCEPT D\u2019<em>\u00c9<\/em>TAT FONCTIONNEL DANS LA LUTTE CONTRE L\u2019INS<em>\u00c9<\/em>CURIT<em>\u00c9<\/em> ALIMENTAIRE EN AFRIQUE<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout en int\u00e9grant le fait qu\u2019il y a des strat\u00e9gies proprement d\u00e9di\u00e9es au d\u00e9veloppement de l\u2019agriculture et \u00e0 la gestion des autres facteurs qui contribuent \u00e0 la persistance des crises alimentaires, l\u2019int\u00e9gration du concept d\u2019Etat fonctionnel pourrait permettre en g\u00e9n\u00e9ral d\u2019avoir&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une r\u00e9conciliation entre le court terme (l\u2019urgence humanitaire) et le long terme (Le d\u00e9veloppement des capacit\u00e9s endog\u00e8nes \u00e0 pr\u00e9venir et surmonter les d\u00e9fis alimentaires)&nbsp;;<\/li>\n\n\n\n<li>Une meilleure utilisation des ressources mobilis\u00e9es pour le d\u00e9veloppement des secteurs li\u00e9s \u00e0 la s\u00e9curit\u00e9 alimentaire en Afrique ;<\/li>\n\n\n\n<li>Une meilleure coordination des interventions des acteurs nationaux et internationaux dans la perspective d\u2019un renforcement effectif de l\u2019Etat (Gouvernement et Collectivit\u00e9s territoriales d\u00e9centralis\u00e9es).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">De mani\u00e8re sp\u00e9cifique, en se r\u00e9f\u00e9rant aux piliers du concept, on peut noter la valeur ajout\u00e9e potentielle ci \u2013 dessous.<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li style=\"text-decoration:underline\"><strong>PRISE EN COMPTE DU PILIER \u00ab&nbsp;PRESENCE&nbsp;\u00bb<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">La prise en compte du pilier \u00ab&nbsp;PRESENCE&nbsp;\u00bb de l\u2019Etat signifie que tout en intervenant pour g\u00e9rer les urgences, on met en place des mesures et dispositifs qui renforcent la pr\u00e9sence de l\u2019Etat dans la zone ou le secteur affect\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les questions suivantes, relatives au pilier \u00ab&nbsp;PRESENCE&nbsp;\u00bb, peuvent aider \u00e0 renforcer la fonctionnalit\u00e9 des Etats&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le minist\u00e8re de l\u2019agriculture (MINAGRI) et les services connexes sont-ils pr\u00e9sents dans les zones agricoles cl\u00e9s ?<\/li>\n\n\n\n<li>Comment le MINAGRI et les principaux services connexes peuvent-ils \u00eatre renforc\u00e9s durablement ?<\/li>\n\n\n\n<li>La collecte de donn\u00e9es sur la population peut-elle \u00eatre int\u00e9gr\u00e9e ? Les programmes de transferts mon\u00e9taires sont-ils l&#8217;occasion de constituer des bases de donn\u00e9es r\u00e9gionales ou nationales pour mieux planifier l&#8217;avenir ?<\/li>\n\n\n\n<li>Les principales infrastructures agricoles peuvent-elles \u00eatre am\u00e9lior\u00e9es ?<\/li>\n\n\n\n<li>Les gouvernements locaux seront-ils plus efficaces en mati\u00e8re de suivi et d&#8217;\u00e9valuation sur leur territoire ?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9sum\u00e9, comment notre intervention permet \u2013 t \u2013 elle de renforcer la pr\u00e9sence et le fonctionnement du MINAGRI dans cette zone&nbsp;?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>PRISE EN COMPTE DU PILIER \u00ab SURETE &amp; SECURITE DURABLES&nbsp;\u00bb<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La prise en compte du pilier \u00ab&nbsp;SURETE ET SECURITE DURABLES&nbsp;\u00bb permet de s\u2019assurer que l\u2019intervention permet de renforcer le respect des droits fondamentaux, le d\u00e9ploiement d\u2019un syst\u00e8me judiciaire fonctionnel, les forces de d\u00e9fenses et de s\u00e9curit\u00e9 au service de la population, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Appliqu\u00e9 dans le cadre de la gestion des crises alimentaires, il s\u2019agit de se poser les questions suivantes&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Les groupes les plus vuln\u00e9rables peuvent-ils int\u00e9grer les processus de prise de d\u00e9cision ?<\/li>\n\n\n\n<li>Les minist\u00e8res peuvent-ils \u00eatre renforc\u00e9s en mati\u00e8re de recrutement, de formation et de promotion du personnel afin de renforcer la pr\u00e9sence de l&#8217;\u00c9tat ?<\/li>\n\n\n\n<li>Les fonctionnaires qui fournissent des services agricoles peuvent-ils \u00eatre form\u00e9s aux droits de l&#8217;homme, \u00e0 l&#8217;\u00e9quit\u00e9 et \u00e0 la justice ?<\/li>\n\n\n\n<li>Les forces de s\u00e9curit\u00e9 impliqu\u00e9es peuvent-elles \u00eatre form\u00e9es \u00e0 un maintien de l&#8217;ordre humain et fond\u00e9 sur les droits de l&#8217;homme ?<\/li>\n\n\n\n<li>Les citoyens peuvent-ils, par l&#8217;interm\u00e9diaire de leurs associations, \u00eatre inform\u00e9s des strat\u00e9gies et des budgets afin de garantir l&#8217;impact et la responsabilit\u00e9 ?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9sum\u00e9, notre intervention permet \u2013 elle de corriger durablement la fa\u00e7on dont les acteurs sont impliqu\u00e9s et les ressources partag\u00e9es&nbsp;?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>PRISE EN COMPTE DU PILIER \u00ab&nbsp;ESPOIR&nbsp;\u00bb<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La prise en compte du pilier \u00ab&nbsp;ESPOIR&nbsp;\u00bb signifie que tout en g\u00e9rant les urgences des crises alimentaires et humanitaires, on d\u00e9veloppe les bases du d\u00e9veloppement d\u2019un environnement des affaires et d\u2019unit\u00e9s \u00e9conomiques capables de cr\u00e9er des richesses et des emplois dans la dur\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans cette perspective, les questions suivantes peuvent \u00eatre pos\u00e9es&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comment la technologie est-elle int\u00e9gr\u00e9e pour renforcer l&#8217;\u00c9tat ?<\/li>\n\n\n\n<li>Comment les startups, les cr\u00e9atifs sont-ils int\u00e9gr\u00e9s, renforc\u00e9s et leur relation avec l&#8217;\u00c9tat \u00e9quilibr\u00e9e \u00e0 travers le processus ?<\/li>\n\n\n\n<li>Des entreprises viables peuvent-elles \u00eatre cr\u00e9\u00e9es ou renforc\u00e9es dans le cadre du processus ?<\/li>\n\n\n\n<li>Comment l&#8217;art et la culture ont-ils \u00e9t\u00e9 renforc\u00e9s dans le processus et int\u00e9gr\u00e9s en tant qu&#8217;\u00e9l\u00e9ment essentiel de l&#8217;\u00c9tat ?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9sum\u00e9, comment on s\u2019assure d\u2019identifier et de d\u00e9velopper aussi bien les conditions favorables au d\u00e9veloppement \u00e9conomique et l\u2019\u00e9mergence d\u2019entrepreneurs capables de r\u00e9ussir dans la dur\u00e9e&nbsp;?<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"background:linear-gradient(100deg,rgb(6,147,227) 0%,rgb(246,246,246) 100%);font-size:20px;font-style:italic;font-weight:800\"><strong><em>EN GUISE DE CONCLUSION<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En d\u00e9finitive, la prise en compte de l\u2019Etat fonctionnel dans le cadre du d\u00e9ploiement de tout projet dans les pays africains est importante et n\u00e9cessaire dans la mesure o\u00f9 elle permettrait&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une meilleure \u00e9laboration des projets&nbsp;\u00e0 travers l\u2019implication des diff\u00e9rentes parties prenantes dont les b\u00e9n\u00e9ficiaires qui sont les mieux \u00e0 m\u00eame de formuler leurs besoins et la meilleure fa\u00e7on de les r\u00e9soudre&nbsp;;<\/li>\n\n\n\n<li>Une meilleure collaboration entre l\u2019ensemble des acteurs du syst\u00e8mes impliqu\u00e9s dans la mise en \u0153uvre du projet au moment de son impl\u00e9mentation&nbsp;;<\/li>\n\n\n\n<li>L\u2019atteinte des objectifs \u00e0 travers des r\u00e9sultats satisfaisants et durables.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Pour ces raisons, STRATEGIES recommande fortement que&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La fonctionnalit\u00e9 de l&#8217;\u00c9tat soit prise en compte dans le cadre de l&#8217;analyse, de la strat\u00e9gie et des actions de mise en \u0153uvre.<\/li>\n\n\n\n<li>La fonctionnalit\u00e9 de l&#8217;\u00c9tat doit faire partie des r\u00e9ponses humanitaires (\u00e0 court terme) et de d\u00e9veloppement (\u00e0 plus long terme).<\/li>\n\n\n\n<li>La fonctionnalit\u00e9 doit faire partie des discussions au sein des organisations des \u00c9tats membres, des n\u00e9gociations bilat\u00e9rales et des programmes.<\/li>\n\n\n\n<li>Les niveaux d\u00e9centralis\u00e9s de gouvernement doivent faire partie des solutions d\u00e8s leur conception.<\/li>\n\n\n\n<li>Les citoyens (associations, syndicats, secteur priv\u00e9, ONG&#8230;) soient int\u00e9gr\u00e9s de la conception \u00e0 la mise en \u0153uvre et \u00e0 l&#8217;\u00e9valuation de l&#8217;impact et de la responsabilit\u00e9.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nous en sommes convaincus, des Etats fonctionnels en Afrique seront certainement plus efficaces pour relever le d\u00e9fi de l\u2019ins\u00e9curit\u00e9 alimentaire.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a id=\"_edn1\" href=\"#_ednref1\">[i]<\/a>Source&nbsp;:<a href=\"https:\/\/www.fao.org\/hunger\/fr\/#:~:text=Qu'est%2Dce%20que%20l,une%20vie%20active%20et%20saine\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.fao.org\/hunger\/fr\/#:~:text=Qu&#8217;est%2Dce%20que%20l,une%20vie%20active%20et%20saine<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ednref1\">[ii]<\/a> Source&nbsp;: <a href=\"https:\/\/www.wfp.org\/publications\/global-report-food-crises-2021\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.wfp.org\/publications\/global-report-food-crises-2021<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ednref3\">[iii]<\/a> Source&nbsp;: <a href=\"https:\/\/www.oxfamfrance.org\/agriculture-et-securite-alimentaire\/faim-dans-le-monde-causes-consequences-solutions\/#:~:text=Conflits%2C%20changements%20climatiques%2C%20in%C3%A9galit%C3%A9s%20%3A,personnes%20dans%20le%20monde%207\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.oxfamfrance.org\/agriculture-et-securite-alimentaire\/faim-dans-le-monde-causes-consequences-solutions\/#:~:text=Conflits%2C%20changements%20climatiques%2C%20in%C3%A9galit%C3%A9s%20%3A,personnes%20dans%20le%20monde%207<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I &#8211; ETAT DES LIEUX DE INS\u00c9CURIT\u00c9 ALIMENTAIRE EN AFRIQUE De fa\u00e7on concr\u00e8te, l\u2019ins\u00e9curit\u00e9 alimentaire existe lorsque des personnes n&#8217;ont pas un acc\u00e8s physique ou \u00e9conomique durable \u00e0 une nourriture suffisamment s\u00fbre, nutritive et socialement acceptable pour mener une vie saine et productive. L\u2019ins\u00e9curit\u00e9 alimentaire connait plusieurs degr\u00e9s de s\u00e9v\u00e9rit\u00e9 comme l\u2019indique le tableau ci<\/p>\n","protected":false},"author":4,"featured_media":10337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0? - STRATEGIES! Consulting Firm<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0? - STRATEGIES! Consulting Firm\" \/>\n<meta property=\"og:description\" content=\"I &#8211; ETAT DES LIEUX DE INS\u00c9CURIT\u00c9 ALIMENTAIRE EN AFRIQUE De fa\u00e7on concr\u00e8te, l\u2019ins\u00e9curit\u00e9 alimentaire existe lorsque des personnes n&#8217;ont pas un acc\u00e8s physique ou \u00e9conomique durable \u00e0 une nourriture suffisamment s\u00fbre, nutritive et socialement acceptable pour mener une vie saine et productive. L\u2019ins\u00e9curit\u00e9 alimentaire connait plusieurs degr\u00e9s de s\u00e9v\u00e9rit\u00e9 comme l\u2019indique le tableau ci\" \/>\n<meta property=\"og:url\" content=\"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/\" \/>\n<meta property=\"og:site_name\" content=\"STRATEGIES! Consulting Firm\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cabinetstrategies\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-17T09:41:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T10:11:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1453\" \/>\n\t<meta property=\"og:image:height\" content=\"804\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cabinet STRATEGIES\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Strategies_\" \/>\n<meta name=\"twitter:site\" content=\"@Strategies_\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cabinet STRATEGIES\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/\"},\"author\":{\"name\":\"Cabinet STRATEGIES\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#\\\/schema\\\/person\\\/3be6dad1a63aff42aed9ec22b8566797\"},\"headline\":\"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0?\",\"datePublished\":\"2023-07-17T09:41:34+00:00\",\"dateModified\":\"2023-08-30T10:11:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/\"},\"wordCount\":2817,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/crisealim1.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/\",\"url\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/\",\"name\":\"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0? - STRATEGIES! Consulting Firm\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/crisealim1.jpg\",\"datePublished\":\"2023-07-17T09:41:34+00:00\",\"dateModified\":\"2023-08-30T10:11:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/crisealim1.jpg\",\"contentUrl\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/crisealim1.jpg\",\"width\":1453,\"height\":804},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#website\",\"url\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/\",\"name\":\"STRATEGIES! Consulting Firm\",\"description\":\"Your Reference in Leadership and Management\",\"publisher\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#organization\",\"name\":\"STRATEGIES! Consulting Firm\",\"url\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-STRATEGIES-Consulting.png\",\"contentUrl\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-STRATEGIES-Consulting.png\",\"width\":734,\"height\":229,\"caption\":\"STRATEGIES! Consulting Firm\"},\"image\":{\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/cabinetstrategies\",\"https:\\\/\\\/x.com\\\/Strategies_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/strategies-\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/#\\\/schema\\\/person\\\/3be6dad1a63aff42aed9ec22b8566797\",\"name\":\"Cabinet STRATEGIES\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0185eea5d98dd18f3a1a005bba9a370938a8f245c3bb39e8b3997cda435ee11f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0185eea5d98dd18f3a1a005bba9a370938a8f245c3bb39e8b3997cda435ee11f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0185eea5d98dd18f3a1a005bba9a370938a8f245c3bb39e8b3997cda435ee11f?s=96&d=mm&r=g\",\"caption\":\"Cabinet STRATEGIES\"},\"url\":\"https:\\\/\\\/strategiesconsultingfirm.com\\\/fr\\\/author\\\/strategies_cabinet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0? - STRATEGIES! Consulting Firm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/","og_locale":"fr_FR","og_type":"article","og_title":"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0? - STRATEGIES! Consulting Firm","og_description":"I &#8211; ETAT DES LIEUX DE INS\u00c9CURIT\u00c9 ALIMENTAIRE EN AFRIQUE De fa\u00e7on concr\u00e8te, l\u2019ins\u00e9curit\u00e9 alimentaire existe lorsque des personnes n&#8217;ont pas un acc\u00e8s physique ou \u00e9conomique durable \u00e0 une nourriture suffisamment s\u00fbre, nutritive et socialement acceptable pour mener une vie saine et productive. L\u2019ins\u00e9curit\u00e9 alimentaire connait plusieurs degr\u00e9s de s\u00e9v\u00e9rit\u00e9 comme l\u2019indique le tableau ci","og_url":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/","og_site_name":"STRATEGIES! Consulting Firm","article_publisher":"https:\/\/web.facebook.com\/cabinetstrategies","article_published_time":"2023-07-17T09:41:34+00:00","article_modified_time":"2023-08-30T10:11:35+00:00","og_image":[{"width":1453,"height":804,"url":"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim1.jpg","type":"image\/jpeg"}],"author":"Cabinet STRATEGIES","twitter_card":"summary_large_image","twitter_creator":"@Strategies_","twitter_site":"@Strategies_","twitter_misc":{"\u00c9crit par":"Cabinet STRATEGIES","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/#article","isPartOf":{"@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/"},"author":{"name":"Cabinet STRATEGIES","@id":"https:\/\/strategiesconsultingfirm.com\/#\/schema\/person\/3be6dad1a63aff42aed9ec22b8566797"},"headline":"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0?","datePublished":"2023-07-17T09:41:34+00:00","dateModified":"2023-08-30T10:11:35+00:00","mainEntityOfPage":{"@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/"},"wordCount":2817,"commentCount":0,"publisher":{"@id":"https:\/\/strategiesconsultingfirm.com\/#organization"},"image":{"@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/#primaryimage"},"thumbnailUrl":"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim1.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/","url":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/","name":"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0? - STRATEGIES! Consulting Firm","isPartOf":{"@id":"https:\/\/strategiesconsultingfirm.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/#primaryimage"},"image":{"@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/#primaryimage"},"thumbnailUrl":"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim1.jpg","datePublished":"2023-07-17T09:41:34+00:00","dateModified":"2023-08-30T10:11:35+00:00","breadcrumb":{"@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/#primaryimage","url":"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim1.jpg","contentUrl":"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/08\/crisealim1.jpg","width":1453,"height":804},{"@type":"BreadcrumbList","@id":"https:\/\/strategiesconsultingfirm.com\/fr\/faire-face-aux-crises-alimentaires-en-afrique-et-si-lon-travaillait-sur-la-fonctionnalite-des-etats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/strategiesconsultingfirm.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"FAIRE FACE AUX CRISES ALIMENTAIRES EN AFRIQUE\u00a0: ET SI L\u2019ON TRAVAILLAIT SUR LA FONCTIONNALIT\u00c9 DES ETATS\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/strategiesconsultingfirm.com\/#website","url":"https:\/\/strategiesconsultingfirm.com\/","name":"STRATEGIES! Consulting Firm","description":"Your Reference in Leadership and Management","publisher":{"@id":"https:\/\/strategiesconsultingfirm.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/strategiesconsultingfirm.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/strategiesconsultingfirm.com\/#organization","name":"STRATEGIES! Consulting Firm","url":"https:\/\/strategiesconsultingfirm.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/strategiesconsultingfirm.com\/#\/schema\/logo\/image\/","url":"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/05\/Logo-STRATEGIES-Consulting.png","contentUrl":"https:\/\/strategiesconsultingfirm.com\/wp-content\/uploads\/2023\/05\/Logo-STRATEGIES-Consulting.png","width":734,"height":229,"caption":"STRATEGIES! Consulting Firm"},"image":{"@id":"https:\/\/strategiesconsultingfirm.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cabinetstrategies","https:\/\/x.com\/Strategies_","https:\/\/www.linkedin.com\/company\/strategies-\/"]},{"@type":"Person","@id":"https:\/\/strategiesconsultingfirm.com\/#\/schema\/person\/3be6dad1a63aff42aed9ec22b8566797","name":"Cabinet STRATEGIES","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0185eea5d98dd18f3a1a005bba9a370938a8f245c3bb39e8b3997cda435ee11f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0185eea5d98dd18f3a1a005bba9a370938a8f245c3bb39e8b3997cda435ee11f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0185eea5d98dd18f3a1a005bba9a370938a8f245c3bb39e8b3997cda435ee11f?s=96&d=mm&r=g","caption":"Cabinet STRATEGIES"},"url":"https:\/\/strategiesconsultingfirm.com\/fr\/author\/strategies_cabinet\/"}]}},"_links":{"self":[{"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/posts\/10328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/comments?post=10328"}],"version-history":[{"count":12,"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/posts\/10328\/revisions"}],"predecessor-version":[{"id":10422,"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/posts\/10328\/revisions\/10422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/media\/10337"}],"wp:attachment":[{"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/media?parent=10328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/categories?post=10328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/strategiesconsultingfirm.com\/fr\/wp-json\/wp\/v2\/tags?post=10328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}